{"id":11561,"date":"2013-12-23T20:56:08","date_gmt":"2013-12-23T20:56:08","guid":{"rendered":"http:\/\/blog.comparaonline.cl\/?p=11561"},"modified":"2017-10-06T14:53:42","modified_gmt":"2017-10-06T17:53:42","slug":"4-tips-para-mantenerte-seguro-en-la-carretera","status":"publish","type":"post","link":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/","title":{"rendered":"4 Tips para mantenerte seguro en la carretera"},"content":{"rendered":"<p>Manejar en las autopistas es relativamente f\u00e1cil, dado que no existen intersecciones, sem\u00e1foros o peatones en la v\u00eda, por eso hay menos posibilidades de accidentes.<\/p>\n<p>Sin embargo, las colisiones que ocurren causan m\u00e1s da\u00f1os en los veh\u00edculos y personas debido a que las velocidades son m\u00e1s altas. Entonces lo importante es saber c\u00f3mo manejarse all\u00ed afuera, adem\u00e1s de contar con un buen\u00a0<strong><a href=\"https:\/\/www.comparaonline.com\/seguro-automotriz\/seguro-de-auto\" target=\"_blank\">Seguro Automotriz<\/a><\/strong>. A continuaci\u00f3n te brindamos algunos consejos para manejar de modo seguro en las autopistas:<\/p>\n<p><strong>1.- Acelera al ritmo del tr\u00e1fico.<\/strong> Recuerda que la velocidad \u00a0debe estar por debajo del l\u00edmite de velocidad. Y que durante las horas pico, el tr\u00e1fico se hace lento y se debe conducir a la velocidad que va el tr\u00e1nsito y manteniendo distancias prudentes con los dem\u00e1s conductores.<\/p>\n<p><strong>2.- Cede el paso a los conductores que ya est\u00e1n en la autopista.<\/strong> Si quieres incorporarte a una autopista, permanece atento. Quienes est\u00e1n en la autopista tienen derecho a la v\u00eda, aseg\u00farate que tu velocidad coincida con la suya antes de entrar en el tr\u00e1fico. Una vez que est\u00e9s en el carril de circulaci\u00f3n, verifica tu espejo retrovisor para ver si necesitas acelerar, pues el auto que viene detr\u00e1s tuyo podr\u00eda colisionar contigo.<\/p>\n<p><strong>3.- Mant\u00e9n una distancia de 3 a 5 segundos con el coche de adelante.<\/strong> Ten en cuenta que a mayor velocidad necesitas m\u00e1s distancia de frenado y tiempo de reacci\u00f3n. Para calcular la distancia segura puedes optar por ver las l\u00edneas divisorias de carriles. Si ves 3-4 l\u00edneas divisorias blancas entre t\u00fa y el veh\u00edculo que va delante, est\u00e1s de 1-2 segundos por detr\u00e1s de ese veh\u00edculo, de 4-6 l\u00edneas divisorias son 2-3 segundos y 6-8 l\u00edneas son de 3-4 segundos. Al manejar mira lo que pasa delante tuyo unos 20 a 30 segundos, esto es aproximadamente 1 \/2 milla a 55 mph.<\/p>\n<p><strong>4.- Cambio de carril:<\/strong> Espera las l\u00edneas blancas punteadas para hacer un cambio de carril o entrar en la autopista. Dado que el tr\u00e1fico va mucho m\u00e1s r\u00e1pido es importante mantener tu velocidad al cambiar de v\u00eda. Est\u00e1 atento a las motocicletas en el carril al que piensas entrar, recuerda que estas son m\u00e1s peque\u00f1as y dif\u00edciles de ver. Ten en cuenta que podr\u00edan estar en tu punto ciego en los cambios de carril.<\/p>\n<p>Sigue estos consejos para tener una experiencia m\u00e1s tranquila al estar en la autopista y, adem\u00e1s, no te olvides de <b><a href=\"https:\/\/www.comparaonline.com\/seguro-automotriz\/seguro-de-auto\">Contratar Seguros de Auto<\/a><\/b>\u00a0que dupliquen esa tranquilidad. Ahora s\u00ed \u00a1ya est\u00e1s listo para salir a las rutas!<\/p>\n<p>Recuerda que en Compara puedes Cotizar gratis y sin salir de casa un Seguro Automotriz a tu medida. Ingresa a nuestro <a title=\"Cotiza tu Seguro Automotriz aqu\u00ed! \" href=\"https:\/\/www.comparaonline.cl\/seguro-automotriz\"><strong>Comparador de Seguro Auto<\/strong><\/a>, obtendr\u00e1s resultados instant\u00e1neos con las mejores aseguradoras del mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manejar en las autopistas es relativamente f\u00e1cil, dado que no existen intersecciones, sem\u00e1foros o peatones en la v\u00eda, por eso hay menos posibilidades de accidentes.<\/p>\n","protected":false},"author":45,"featured_media":11562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1277],"tags":[],"class_list":["post-11561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguro-automotriz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 Tips para mantenerte seguro en la carretera - ComparaOnline<\/title>\n<meta name=\"description\" content=\"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 Tips para mantenerte seguro en la carretera - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparachile\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-23T20:56:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-06T17:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clara Escobar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_chile\" \/>\n<meta name=\"twitter:site\" content=\"@compara_chile\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clara Escobar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\"},\"author\":{\"name\":\"Clara Escobar\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/2f605442e15d63553e57ec9ee4b9a51f\"},\"headline\":\"4 Tips para mantenerte seguro en la carretera\",\"datePublished\":\"2013-12-23T20:56:08+00:00\",\"dateModified\":\"2017-10-06T17:53:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\"},\"wordCount\":497,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg\",\"articleSection\":[\"Seguro Automotriz\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\",\"url\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\",\"name\":\"4 Tips para mantenerte seguro en la carretera - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg\",\"datePublished\":\"2013-12-23T20:56:08+00:00\",\"dateModified\":\"2017-10-06T17:53:42+00:00\",\"description\":\"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!\",\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg\",\"width\":435,\"height\":288,\"caption\":\"sigue estos consejos y evita accidentes en la carretera\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.cl\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Todo lo que necesitas saber sobre seguros y productos financieros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.cl\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.cl\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparachile\/\",\"https:\/\/x.com\/compara_chile\",\"https:\/\/www.instagram.com\/compara_chile\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"http:\/\/www.youtube.com\/c\/ComparaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/2f605442e15d63553e57ec9ee4b9a51f\",\"name\":\"Clara Escobar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/Clara-Escobar.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/Clara-Escobar.jpg\",\"caption\":\"Clara Escobar\"},\"description\":\"Soy periodista y especialista en seguros, sobretodo si tienen que ver con el mundo automotriz. Los autos me gustan desde siempre y, por lo mismo estoy atenta a su mantenimiento y a las coberturas a considerar.\",\"sameAs\":[\"http:\/\/esteesunusuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.cl\/blog\/author\/clara-escobar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 Tips para mantenerte seguro en la carretera - ComparaOnline","description":"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/","og_locale":"es_ES","og_type":"article","og_title":"4 Tips para mantenerte seguro en la carretera - ComparaOnline","og_description":"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!","og_url":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparachile\/","article_published_time":"2013-12-23T20:56:08+00:00","article_modified_time":"2017-10-06T17:53:42+00:00","og_image":[{"width":435,"height":288,"url":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg","type":"image\/jpeg"}],"author":"Clara Escobar","twitter_card":"summary_large_image","twitter_creator":"@compara_chile","twitter_site":"@compara_chile","twitter_misc":{"Escrito por":"Clara Escobar","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/"},"author":{"name":"Clara Escobar","@id":"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/2f605442e15d63553e57ec9ee4b9a51f"},"headline":"4 Tips para mantenerte seguro en la carretera","datePublished":"2013-12-23T20:56:08+00:00","dateModified":"2017-10-06T17:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/"},"wordCount":497,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.cl\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg","articleSection":["Seguro Automotriz"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/","url":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/","name":"4 Tips para mantenerte seguro en la carretera - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.cl\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg","datePublished":"2013-12-23T20:56:08+00:00","dateModified":"2017-10-06T17:53:42+00:00","description":"Manejar en carretera tiene sus ma\u00f1as. Si no las conoces, puedes sufrir accidentes inc\u00f3modos o incluso graves. Atento a estos 4 consejos fundamentales!","inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.comparaonline.cl\/blog\/autos\/seguro-automotriz\/4-tips-para-mantenerte-seguro-en-la-carretera\/#primaryimage","url":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg","contentUrl":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2014\/01\/tips-conducir-autopista.jpg","width":435,"height":288,"caption":"sigue estos consejos y evita accidentes en la carretera"},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.cl\/blog\/#website","url":"https:\/\/www.comparaonline.cl\/blog\/","name":"ComparaOnline","description":"Todo lo que necesitas saber sobre seguros y productos financieros","publisher":{"@id":"https:\/\/www.comparaonline.cl\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.cl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.cl\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.cl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparachile\/","https:\/\/x.com\/compara_chile","https:\/\/www.instagram.com\/compara_chile\/","https:\/\/www.linkedin.com\/company\/compara\/","http:\/\/www.youtube.com\/c\/ComparaChile"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/2f605442e15d63553e57ec9ee4b9a51f","name":"Clara Escobar","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.comparaonline.cl\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/Clara-Escobar.jpg","contentUrl":"https:\/\/www.comparaonline.cl\/blog-statics\/cl\/uploads\/2020\/02\/Clara-Escobar.jpg","caption":"Clara Escobar"},"description":"Soy periodista y especialista en seguros, sobretodo si tienen que ver con el mundo automotriz. Los autos me gustan desde siempre y, por lo mismo estoy atenta a su mantenimiento y a las coberturas a considerar.","sameAs":["http:\/\/esteesunusuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.cl\/blog\/author\/clara-escobar\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/posts\/11561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/comments?post=11561"}],"version-history":[{"count":0,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/posts\/11561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/media\/11562"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/media?parent=11561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/categories?post=11561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.cl\/blog\/wp-json\/wp\/v2\/tags?post=11561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}